{"id":1549,"date":"2020-03-20T15:13:30","date_gmt":"2020-03-20T14:13:30","guid":{"rendered":"https:\/\/www.kravosguadagno.it\/?p=1549"},"modified":"2024-07-01T01:07:01","modified_gmt":"2024-07-01T01:07:01","slug":"igiene-orale-e-alimentare-nel-bambino","status":"publish","type":"post","link":"https:\/\/www.kravosguadagno.it\/en\/blog\/igiene-orale-e-alimentare-nel-bambino","title":{"rendered":"Igiene orale e alimentare nel bambino"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"320\" src=\"https:\/\/www.kravosguadagno.it\/wp-content\/uploads\/2024\/07\/igiene-orale-consigli.jpg\" alt=\"\" class=\"wp-image-4112\" srcset=\"https:\/\/www.kravosguadagno.it\/wp-content\/uploads\/2024\/07\/igiene-orale-consigli.jpg 640w, https:\/\/www.kravosguadagno.it\/wp-content\/uploads\/2024\/07\/igiene-orale-consigli-300x150.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n<\/div>\n\n<p>\u00a0<\/p>\n<p>Care mamme e cari pap\u00e0,<\/p>\n<p>durante questo periodo difficile in cui tutti noi <strong>#restiamoacasa<\/strong> non dimentichiamo l\u2019importanza di una corretta igiene orale e di un\u2019alimentazione sana ed equilibrata per i nostri bimbi.<\/p>\n<h2>5 utili consigli per non perdere le buone abitudini di igiene orale<\/h2>\n<ol>\n<li>Lavare i dentini almeno 2 volte al giorno dopo i pasti principali ricordando di spazzolare in modo accurato tutte le superfici per 2 minuti, l\u2019utilizzo di una clessidra o l\u2019ascolto di una canzone possono essere utili per la misura del tempo!<\/li>\n<li>Utilizzare uno spazzolino con setole morbide e testina di dimensioni adeguate in base all\u2019et\u00e0 del bambino (testina piccola fino ai 6 anni), nel neonato \u00e8 consigliato detergere le gengive con una garzina inumidita dopo la poppata<\/li>\n<li>Utilizzare una dose corretta di dentifricio al fluoro sempre sotto controllo del genitore, chicco di riso (rice grain size) da 0 a 3 anni, pisellino (pea size) da 3 a 6 anni. Dopo i 6 anni il riflesso della deglutizione \u00e8 completamente sviluppato e non vi \u00e8 rischio d\u2019ingestione<\/li>\n<li>Ridurre la quantit\u00e0 e la frequenza di assunzione di cibi e\/o di bevande zuccherate. Lo scopo non \u00e8 quello di modificare l\u2019apporto nutritizio al bambino ma di limitare l\u2019apporto glucidico secondario<\/li>\n<li>Preferire fuori pasto il consumo di cibi e\/o di bevande non zuccherate e non gassate, attenzione a non far addormentare il bambino con il biberon contenente latte, succo, th\u00e8 in bocca!<\/li>\n<\/ol>\n<h3>Ricordiamoci inoltre che<\/h3>\n<ul>\n<li>Il genitore deve supervisionare e aiutare il bambino durante le manovre di igiene orale fino all\u2019acquisizione di una manualit\u00e0 adeguata!<\/li>\n<li>Lo spazzolino \u00e8 personale! Ognuno deve usare il proprio spazzolino e non scambiarlo!!<\/li>\n<li>I bambini imparano per imitazione! Dobbiamo essere noi a dare loro il buon esempio!<\/li>\n<\/ul>\n<hr \/>\n<p>Articolo redatto dalla <a href=\"https:\/\/www.kravosguadagno.it\/team\/dott-ssa-valentina-luppieri\/\">Dott.ssa Valentina Luppieri<\/a><\/p>\n<p>Specialista in odontoiatria pediatrica<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a0 Care mamme e cari pap\u00e0, durante questo periodo difficile in cui tutti noi #restiamoacasa non dimentichiamo l\u2019importanza di una corretta igiene orale e&#8230;<\/p>\n","protected":false},"author":1,"featured_media":4112,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[49],"tags":[],"class_list":["post-1549","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consigli"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Igiene orale e alimentare nel bambino - Kravos &amp; Guadagno<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kravosguadagno.it\/en\/blog\/igiene-orale-e-alimentare-nel-bambino\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Igiene orale e alimentare nel bambino - Kravos &amp; Guadagno\" \/>\n<meta property=\"og:description\" content=\"\u00a0 Care mamme e cari pap\u00e0, durante questo periodo difficile in cui tutti noi #restiamoacasa non dimentichiamo l\u2019importanza di una corretta igiene orale e...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kravosguadagno.it\/en\/blog\/igiene-orale-e-alimentare-nel-bambino\" \/>\n<meta property=\"og:site_name\" content=\"Kravos &amp; Guadagno\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KravosGuadagno\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-20T14:13:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-01T01:07:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kravosguadagno.it\/wp-content\/uploads\/2024\/07\/igiene-orale-consigli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"320\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"interlaced\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"interlaced\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kravosguadagno.it\\\/en\\\/blog\\\/igiene-orale-e-alimentare-nel-bambino#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kravosguadagno.it\\\/en\\\/blog\\\/igiene-orale-e-alimentare-nel-bambino\"},\"author\":{\"name\":\"interlaced\",\"@id\":\"https:\\\/\\\/www.kravosguadagno.it\\\/#\\\/schema\\\/person\\\/0bfa944880f292e8a7481bd2d8fae015\"},\"headline\":\"Igiene orale e alimentare nel bambino\",\"datePublished\":\"2020-03-20T14:13:30+00:00\",\"dateModified\":\"2024-07-01T01:07:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kravosguadagno.it\\\/en\\\/blog\\\/igiene-orale-e-alimentare-nel-bambino\"},\"wordCount\":296,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kravosguadagno.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kravosguadagno.it\\\/en\\\/blog\\\/igiene-orale-e-alimentare-nel-bambino#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kravosguadagno.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/igiene-orale-consigli.jpg\",\"articleSection\":[\"Consigli\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kravosguadagno.it\\\/en\\\/blog\\\/igiene-orale-e-alimentare-nel-bambino\",\"url\":\"https:\\\/\\\/www.kravosguadagno.it\\\/en\\\/blog\\\/igiene-orale-e-alimentare-nel-bambino\",\"name\":\"Igiene orale e alimentare nel bambino - Kravos &amp; Guadagno\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kravosguadagno.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kravosguadagno.it\\\/en\\\/blog\\\/igiene-orale-e-alimentare-nel-bambino#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kravosguadagno.it\\\/en\\\/blog\\\/igiene-orale-e-alimentare-nel-bambino#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kravosguadagno.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/igiene-orale-consigli.jpg\",\"datePublished\":\"2020-03-20T14:13:30+00:00\",\"dateModified\":\"2024-07-01T01:07:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kravosguadagno.it\\\/en\\\/blog\\\/igiene-orale-e-alimentare-nel-bambino#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kravosguadagno.it\\\/en\\\/blog\\\/igiene-orale-e-alimentare-nel-bambino\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.kravosguadagno.it\\\/en\\\/blog\\\/igiene-orale-e-alimentare-nel-bambino#primaryimage\",\"url\":\"https:\\\/\\\/www.kravosguadagno.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/igiene-orale-consigli.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kravosguadagno.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/igiene-orale-consigli.jpg\",\"width\":640,\"height\":320},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kravosguadagno.it\\\/en\\\/blog\\\/igiene-orale-e-alimentare-nel-bambino#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kravosguadagno.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Igiene orale e alimentare nel bambino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kravosguadagno.it\\\/#website\",\"url\":\"https:\\\/\\\/www.kravosguadagno.it\\\/\",\"name\":\"Kravos & Guadagno\",\"description\":\"Studio Kravos &amp; Guadagno - Dentista a Trieste\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kravosguadagno.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kravosguadagno.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kravosguadagno.it\\\/#organization\",\"name\":\"Kravos & Guadagno\",\"url\":\"https:\\\/\\\/www.kravosguadagno.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.kravosguadagno.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kravosguadagno.it\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/logo-kravos-guadagno.png\",\"contentUrl\":\"https:\\\/\\\/www.kravosguadagno.it\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/logo-kravos-guadagno.png\",\"width\":224,\"height\":85,\"caption\":\"Kravos & Guadagno\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kravosguadagno.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/KravosGuadagno\\\/\",\"https:\\\/\\\/www.instagram.com\\\/kravos_guadagno\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCKZu-vP_VeoO8rWKdm23oow\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kravosguadagno.it\\\/#\\\/schema\\\/person\\\/0bfa944880f292e8a7481bd2d8fae015\",\"name\":\"interlaced\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ba4cc18d2f48555cfe5c04fe43d54e885364e91c7ae23d1b717767c3e879718?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ba4cc18d2f48555cfe5c04fe43d54e885364e91c7ae23d1b717767c3e879718?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ba4cc18d2f48555cfe5c04fe43d54e885364e91c7ae23d1b717767c3e879718?s=96&d=mm&r=g\",\"caption\":\"interlaced\"},\"sameAs\":[\"https:\\\/\\\/www.kravosguadagno.it\"],\"url\":\"https:\\\/\\\/www.kravosguadagno.it\\\/en\\\/blog\\\/author\\\/interlaced\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Igiene orale e alimentare nel bambino - Kravos &amp; Guadagno","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kravosguadagno.it\/en\/blog\/igiene-orale-e-alimentare-nel-bambino","og_locale":"en_US","og_type":"article","og_title":"Igiene orale e alimentare nel bambino - Kravos &amp; Guadagno","og_description":"\u00a0 Care mamme e cari pap\u00e0, durante questo periodo difficile in cui tutti noi #restiamoacasa non dimentichiamo l\u2019importanza di una corretta igiene orale e...","og_url":"https:\/\/www.kravosguadagno.it\/en\/blog\/igiene-orale-e-alimentare-nel-bambino","og_site_name":"Kravos &amp; Guadagno","article_publisher":"https:\/\/www.facebook.com\/KravosGuadagno\/","article_published_time":"2020-03-20T14:13:30+00:00","article_modified_time":"2024-07-01T01:07:01+00:00","og_image":[{"width":640,"height":320,"url":"https:\/\/www.kravosguadagno.it\/wp-content\/uploads\/2024\/07\/igiene-orale-consigli.jpg","type":"image\/jpeg"}],"author":"interlaced","twitter_card":"summary_large_image","twitter_misc":{"Written by":"interlaced","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kravosguadagno.it\/en\/blog\/igiene-orale-e-alimentare-nel-bambino#article","isPartOf":{"@id":"https:\/\/www.kravosguadagno.it\/en\/blog\/igiene-orale-e-alimentare-nel-bambino"},"author":{"name":"interlaced","@id":"https:\/\/www.kravosguadagno.it\/#\/schema\/person\/0bfa944880f292e8a7481bd2d8fae015"},"headline":"Igiene orale e alimentare nel bambino","datePublished":"2020-03-20T14:13:30+00:00","dateModified":"2024-07-01T01:07:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kravosguadagno.it\/en\/blog\/igiene-orale-e-alimentare-nel-bambino"},"wordCount":296,"publisher":{"@id":"https:\/\/www.kravosguadagno.it\/#organization"},"image":{"@id":"https:\/\/www.kravosguadagno.it\/en\/blog\/igiene-orale-e-alimentare-nel-bambino#primaryimage"},"thumbnailUrl":"https:\/\/www.kravosguadagno.it\/wp-content\/uploads\/2024\/07\/igiene-orale-consigli.jpg","articleSection":["Consigli"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.kravosguadagno.it\/en\/blog\/igiene-orale-e-alimentare-nel-bambino","url":"https:\/\/www.kravosguadagno.it\/en\/blog\/igiene-orale-e-alimentare-nel-bambino","name":"Igiene orale e alimentare nel bambino - Kravos &amp; Guadagno","isPartOf":{"@id":"https:\/\/www.kravosguadagno.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kravosguadagno.it\/en\/blog\/igiene-orale-e-alimentare-nel-bambino#primaryimage"},"image":{"@id":"https:\/\/www.kravosguadagno.it\/en\/blog\/igiene-orale-e-alimentare-nel-bambino#primaryimage"},"thumbnailUrl":"https:\/\/www.kravosguadagno.it\/wp-content\/uploads\/2024\/07\/igiene-orale-consigli.jpg","datePublished":"2020-03-20T14:13:30+00:00","dateModified":"2024-07-01T01:07:01+00:00","breadcrumb":{"@id":"https:\/\/www.kravosguadagno.it\/en\/blog\/igiene-orale-e-alimentare-nel-bambino#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kravosguadagno.it\/en\/blog\/igiene-orale-e-alimentare-nel-bambino"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.kravosguadagno.it\/en\/blog\/igiene-orale-e-alimentare-nel-bambino#primaryimage","url":"https:\/\/www.kravosguadagno.it\/wp-content\/uploads\/2024\/07\/igiene-orale-consigli.jpg","contentUrl":"https:\/\/www.kravosguadagno.it\/wp-content\/uploads\/2024\/07\/igiene-orale-consigli.jpg","width":640,"height":320},{"@type":"BreadcrumbList","@id":"https:\/\/www.kravosguadagno.it\/en\/blog\/igiene-orale-e-alimentare-nel-bambino#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kravosguadagno.it\/"},{"@type":"ListItem","position":2,"name":"Igiene orale e alimentare nel bambino"}]},{"@type":"WebSite","@id":"https:\/\/www.kravosguadagno.it\/#website","url":"https:\/\/www.kravosguadagno.it\/","name":"Kravos & Guadagno","description":"Studio Kravos &amp; Guadagno - Dentista a Trieste","publisher":{"@id":"https:\/\/www.kravosguadagno.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kravosguadagno.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.kravosguadagno.it\/#organization","name":"Kravos & Guadagno","url":"https:\/\/www.kravosguadagno.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.kravosguadagno.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.kravosguadagno.it\/wp-content\/uploads\/2023\/12\/logo-kravos-guadagno.png","contentUrl":"https:\/\/www.kravosguadagno.it\/wp-content\/uploads\/2023\/12\/logo-kravos-guadagno.png","width":224,"height":85,"caption":"Kravos & Guadagno"},"image":{"@id":"https:\/\/www.kravosguadagno.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KravosGuadagno\/","https:\/\/www.instagram.com\/kravos_guadagno\/","https:\/\/www.youtube.com\/channel\/UCKZu-vP_VeoO8rWKdm23oow"]},{"@type":"Person","@id":"https:\/\/www.kravosguadagno.it\/#\/schema\/person\/0bfa944880f292e8a7481bd2d8fae015","name":"interlaced","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/0ba4cc18d2f48555cfe5c04fe43d54e885364e91c7ae23d1b717767c3e879718?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0ba4cc18d2f48555cfe5c04fe43d54e885364e91c7ae23d1b717767c3e879718?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0ba4cc18d2f48555cfe5c04fe43d54e885364e91c7ae23d1b717767c3e879718?s=96&d=mm&r=g","caption":"interlaced"},"sameAs":["https:\/\/www.kravosguadagno.it"],"url":"https:\/\/www.kravosguadagno.it\/en\/blog\/author\/interlaced"}]}},"_links":{"self":[{"href":"https:\/\/www.kravosguadagno.it\/en\/wp-json\/wp\/v2\/posts\/1549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kravosguadagno.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kravosguadagno.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kravosguadagno.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kravosguadagno.it\/en\/wp-json\/wp\/v2\/comments?post=1549"}],"version-history":[{"count":2,"href":"https:\/\/www.kravosguadagno.it\/en\/wp-json\/wp\/v2\/posts\/1549\/revisions"}],"predecessor-version":[{"id":4115,"href":"https:\/\/www.kravosguadagno.it\/en\/wp-json\/wp\/v2\/posts\/1549\/revisions\/4115"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kravosguadagno.it\/en\/wp-json\/wp\/v2\/media\/4112"}],"wp:attachment":[{"href":"https:\/\/www.kravosguadagno.it\/en\/wp-json\/wp\/v2\/media?parent=1549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kravosguadagno.it\/en\/wp-json\/wp\/v2\/categories?post=1549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kravosguadagno.it\/en\/wp-json\/wp\/v2\/tags?post=1549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}